{"id":1149,"date":"2016-07-21T19:00:09","date_gmt":"2016-07-21T19:00:09","guid":{"rendered":"http:\/\/www.marcelajardon.net\/2016\/?p=1149"},"modified":"2026-05-05T15:13:53","modified_gmt":"2026-05-05T15:13:53","slug":"corpus","status":"publish","type":"post","link":"https:\/\/www.marcelajardon.net\/2016\/corpus\/","title":{"rendered":"Corpus"},"content":{"rendered":"<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1149-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.marcelajardon.net\/videos\/mpg4\/corpusW.mp4?_=1\" \/><a href=\"http:\/\/www.marcelajardon.net\/videos\/mpg4\/corpusW.mp4\">http:\/\/www.marcelajardon.net\/videos\/mpg4\/corpusW.mp4<\/a><\/video><\/div>\n<p class=\"textes\" align=\"justify\">TITULO PROYECTO: corpus. Construcci\u00f3n digital para tres pantallas.<br \/>\nPAIS Espa\u00f1a<br \/>\nA\u00d1O 2005<br \/>\nSUBTITULOS Castellano<br \/>\nDURACION EN MINUTOS 3&#8217;41<span class=\"textes\"><br \/>\nSINOPSIS Castellano<br \/>\n<\/span><em>-para que ir a tu casa, si puedo verte en el chat?<\/em><br \/>\nEntrar en la red, comunicarse, trabajar &#8216;en&#8217; digital son formas de habitar la realidad virtual, que producen una construcci\u00f3n de la realidad diferente, (combinaci\u00f3n de la &#8216;realidad virtual&#8217; y la &#8216;verdadera realidad&#8217;) a partir de una diferente percepci\u00f3n del tiempo y del espacio, y por todo esto, una diferente percepci\u00f3n del cuerpo. El &#8216;cuerpo&#8217; no se mueve, m\u00e1s bien permanece ext\u00e1tico, se iconiza en la pantalla, donde se reconfigura hasta disolverse, a la vez que se vuelve pantalla. Ve, recorre, controla, &#8216;siente&#8217;, presencia, habita otros lugares, a traves de la pantalla. Cada vez m\u00e1s &#8216;leemos&#8217; la realidad en las pantallas.<\/p>\n<p class=\"textes\" style=\"text-align: left;\" align=\"justify\">El cuerpo siempre ha sido objeto de manipulaci\u00f3n, de recreaci\u00f3n y perversi\u00f3n constantes. Pero el cuerpo es m\u00e1s que el cuerpo. Se lo puede pensar como soporte material de expresiones que est\u00e1n m\u00e1s all\u00e1 del cuerpo. Y cuando toda la realidad tiende a la desmaterializaci\u00f3n, aparecen por un lado las formulas moleculares, las ecuaciones num\u00e9ricas que traducen el cuerpo a una abstracci\u00f3n, y por otro, la mediaci\u00f3n que lo convierte en telem\u00e1tico. Pero a pesar de haber analizado cada part\u00edcula, de casi poder sintetizarlo en un laboratorio, de\u00a0 poder \u00abentrar\u00bb\u00a0 e interactuar con las redes inform\u00e1ticas, el cuerpo se nos escapa. Porque al no ser factible de formular en abstracto el cuerpo de deseo queda omiso en las formulas e interceptado en la realidad.<br \/>\n<em>&#8216;ser un cuerpo es estar unido a un mundo determinado&#8217;<\/em>. m.merleau-ponty<\/p>\n<p align=\"left\"><span class=\"textes\">NOTAS\/COMENTARIOS<br \/>\nProyectado en:<br \/>\n-VIDEO SHORTS,8 de julio de 2007 ,OT301, Overtoom 301, 1054 HW Amsterdam.<br \/>\n-Proyecciones, red03, Centro C\u00edvico San Agust\u00edn, 2007<br \/>\n-VIDIFESTIVAL06 &#8211; International VideoArt Festival of Valencia 05.11.2006<br \/>\n-preBEM, Festival de V\u00eddeo, Burgos, 2006<\/span><\/p>\n<p>VIDEO DATA<br \/>\nTITLE: corpus.<br \/>\nCOUNTRY Spain<br \/>\nYEAR 2005<br \/>\nSUBTITLES no<br \/>\nDURATION 3&#8217;41<br \/>\nSYNOPSIS<br \/>\n<em>-Why I go to your house? If I can see you in the chat?<br \/>\n<\/em>Enter the network, communicate, work &#8216;in&#8217; digital are ways of inhabiting virtual reality, producing a construction of reality different (combination of &#8216;virtual reality&#8217; and &#8216;true reality&#8217;) from a different perception time and space, and all this, a different perception of the body. The &#8216;body&#8217; does not move, rather remains ecstatic, is iconizes on the screen, where it is reconfigured until dissolved, while screen turns. Go walking, controls, &#8216;feels&#8217; presence dwells elsewhere, through the screen. Increasingly &#8216;read&#8217; the reality on the screens.<br \/>\n<em>\u00abbeing a body is to be attached to a given world\u00bb<\/em>. m.merleau-ponty<\/p>\n<div>\n<div class=\"\u201drow\u201d\">\n<div>\n<p align=\"left\">NOTES\/COMMENTS<br \/>\nScreened in:<br \/>\n-VIDEO SHORTS,8 de julio de 2007 ,OT301, Overtoom 301, 1054 HW Amsterdam.<br \/>\n-Proyecciones, red03, Centro C\u00edvico San Agust\u00edn, 2007<br \/>\n-VIDIFESTIVAL06 &#8211; International VideoArt Festival of Valencia 05.11.2006<br \/>\n-preBEM, Festival de V\u00eddeo, Burgos, 2006<\/p>\n<p><iframe loading=\"lazy\" title=\"corpus. Marcela Jard\u00f3n.\" width=\"1620\" height=\"911\" src=\"https:\/\/www.youtube.com\/embed\/Jxc-hWERihw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nTITULO PROYECTO: corpus. Construcci\u00f3n digital para tres pantallas. PAIS Espa\u00f1a A\u00d1O 2005 SUBTITULOS Castellano DURACION EN MINUTOS 3&#8217;41 SINOPSIS Castellano -para que ir a tu casa, si puedo verte en el chat? Entrar en la red, comunicarse, trabajar &#8216;en&#8217; digital son formas de habitar la realidad virtual, que producen una construcci\u00f3n de la realidad diferente,&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.marcelajardon.net\/2016\/corpus\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Corpus&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":1151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[270,100,265,10],"tags":[],"class_list":["post-1149","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-habeas-corpus","category-corpus","category-azules-projects-2026","category-video","post_format-post-format-video","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/1149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/comments?post=1149"}],"version-history":[{"count":5,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/1149\/revisions"}],"predecessor-version":[{"id":3253,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/1149\/revisions\/3253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/media\/1151"}],"wp:attachment":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/media?parent=1149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/categories?post=1149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/tags?post=1149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}