{"id":2034,"date":"2018-10-16T23:09:43","date_gmt":"2018-10-16T23:09:43","guid":{"rendered":"http:\/\/www.marcelajardon.net\/2016\/?p=2034"},"modified":"2023-03-09T16:32:37","modified_gmt":"2023-03-09T16:32:37","slug":"ejercicios-para-una-comprension-del-espacio-tiempo-mirando-el-negativo","status":"publish","type":"post","link":"https:\/\/www.marcelajardon.net\/2016\/ejercicios-para-una-comprension-del-espacio-tiempo-mirando-el-negativo\/","title":{"rendered":"Ejercicios para una comprensi\u00f3n del espacio-tiempo (mirando el negativo)"},"content":{"rendered":"<p>Parto nuevamente de la proposici\u00f3n l\u00f3gica de que el espacio-tiempo est\u00e1 fundado en los diferentes potenciales asumidos.<br \/>\nlas diferencias de potencial generan el movimiento, y hacen que se produzcan diferentes densidades.<br \/>\nlas diferentes densidades provocan nodos perceptibles en un espacio-tiempo determinado.<br \/>\nTodo el tiempo cabe en un instante.<br \/>\nSi el tiempo cabe en un instante, el espacio cabe en un punto.<br \/>\nEl tiempo se abre y ralentiza al aumentar las dimensiones: una dimensi\u00f3n (punto hiperconvergente) es mucho mas veloz que dos dimensiones(plano)<br \/>\ny a la vez, dos dimensiones son m\u00e1s veloces que tres.<\/p>\n<p>Estos ejercicios, convertidos en dibujos, conforman una obra que no va enfocada a un observador<br \/>\ndeterminado. no van enfocados a un receptor concreto.<\/p>\n<p>Son fragmentos de un mensaje emitido al Vac\u00edo.<br \/>\nUn mensaje emitido a un receptor indetefinido (desconocido)<br \/>\nPero, si viene del negativo, no es un mensaje generado por mi.<\/p>\n<p>Por un lado, es un mensaje emitido desde mi negativo hacia mi positivo, pero tambien<br \/>\nes un mensaje desde mi negativo hacia otros negativos,<br \/>\ny hacia otros positivos que reciben la misma frecuencia desde su propio negativo.<\/p>\n<p>El prop\u00f3sito es previo a la existencia.<\/p>\n<p>Lo que est\u00e1 inconsciente es sincronizar un prop\u00f3sito.<br \/>\nCada obra es un intento de sincronizar un prop\u00f3sito inconsciente, modificando un dise\u00f1o,<br \/>\ny hacerlo conciente.<\/p>\n<p>El prop\u00f3sito se vuelve impulso, que se vuelve gesto, que se vuelve trazo, y genera el espacio.<\/p>\n<p>Cada ejercicio genera un espacio-tiempo.<\/p>\n<p>el espacio es el escenario para el desarrollo del tiempo.<\/p>\n<p>cada ejercicio propone una nueva versi\u00f3n que recrea un espacio-tiempo determinado.<\/p>\n<p>Barcelona, 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nParto nuevamente de la proposici\u00f3n l\u00f3gica de que el espacio-tiempo est\u00e1 fundado en los diferentes potenciales asumidos. las diferencias de potencial generan el movimiento, y hacen que se produzcan diferentes densidades. las diferentes densidades provocan nodos perceptibles en un espacio-tiempo determinado. Todo el tiempo cabe en un instante. Si el tiempo cabe en un instante,&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.marcelajardon.net\/2016\/ejercicios-para-una-comprension-del-espacio-tiempo-mirando-el-negativo\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Ejercicios para una comprensi\u00f3n del espacio-tiempo (mirando el negativo)&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-2034","post","type-post","status-publish","format-standard","hentry","category-textos","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/2034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/comments?post=2034"}],"version-history":[{"count":1,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/2034\/revisions"}],"predecessor-version":[{"id":2035,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/2034\/revisions\/2035"}],"wp:attachment":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/media?parent=2034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/categories?post=2034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/tags?post=2034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}