{"id":267,"date":"2016-07-11T13:25:13","date_gmt":"2016-07-11T13:25:13","guid":{"rendered":"http:\/\/www.marcelajardon.net\/2016\/?p=267"},"modified":"2026-05-12T12:20:28","modified_gmt":"2026-05-12T12:20:28","slug":"azules","status":"publish","type":"post","link":"https:\/\/www.marcelajardon.net\/2016\/azules\/","title":{"rendered":"azules"},"content":{"rendered":"<div class=\"titols\" align=\"justify\"><span style=\"color: #ffffff;\">azules<\/span><\/div>\n<div class=\"titols\" align=\"justify\">algunas cuestiones de la realidad circundante, y particularmente, las relaciones cotidianas que estamos estableciendo con la tecnolog\u00eda. Como se convierte en extensiones de nuestros cuerpos, de nuestros sentidos, de nuestras sensaciones, y como acude ante nuestras necesidades de comunicaci\u00f3n, de seguridad, de afecto, de placer, pero no deja de ser virtual, no deja de ser fr\u00eda. Creo que estamos en un punto sutilmente peligroso de endiosamiento de \u00ablo virtual\u00bb y me interesa reflexionar sobre ello.<\/div>\n<div class=\"titols\" align=\"justify\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/div>\n<div align=\"justify\"><\/div>\n<div class=\"titols\" align=\"justify\"><em>some issues surrounding reality, and particularly everyday relationships that we establish with technology. As you become extensions of our bodies, our senses, our feelings, and go to our needs as communications, security, affection, pleasure, but it is still virtual, it is still cold. I think we&#8217;re in a subtly dangerous point of deification of \u00abvirtual\u00bb and think about it interested me.<\/em><\/div>\n<div class=\"titols\" align=\"justify\"><em>Fotomontaje Digital, 2003<\/em><\/div>\n<div align=\"justify\"><\/div>\n<div style=\"text-align: right;\" align=\"justify\">Realitzades durant la celebraci\u00f3 de la BCN Party 2002<\/div>\n<div class=\"titols\" align=\"justify\"><\/div>\n<div id='gallery-1' class='gallery galleryid-267 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0020aa.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0020aa-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0020aa-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0020aa-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0020aa-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0020aa-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0020aa-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0026ae.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0026ae-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0026ae-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0026ae-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0026ae-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0026ae-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0026ae-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0057ae.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0057ae-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0057ae-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0057ae-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0057ae-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0057ae-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0057ae-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0058e.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0058e-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0058e-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0058e-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0058e-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0058e-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0058e-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul3.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul3-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul3-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul3-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul3-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul3-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul4.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul4-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul4-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul4-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul4-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul4-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul11.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul11-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul11-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul11-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul11-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/azul11-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0005ae.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0005ae-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0005ae-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0005ae-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0005ae-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0005ae-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0005ae-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0008e.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0008e-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0008e-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0008e-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0008e-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0008e-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0008e-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0012be.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0012be-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0012be-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0012be-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0012be-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0012be-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0012be-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0013ae.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0013ae-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0013ae-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0013ae-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0013ae-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0013ae-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0013ae-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0015e.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0015e-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0015e-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0015e-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0015e-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0015e-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/2016\/07\/0015e-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<blockquote>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.marcelajardon.com\/categoria-producto\/fotografias\/series\/azules\/\" target=\"_blank\" rel=\"noopener\">&gt;&gt;shop<\/a><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>\u00b7 Punt multim\u00e8dia, Barcelona 2003.<\/p>\n<div align=\"justify\">\n<div id='gallery-2' class='gallery galleryid-267 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/24-1.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/24-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/12.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/16-1.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/16-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/8-2.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/8-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/7-2.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/7-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/25.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>\u00b7 Entrevista en El \u00c1ngel Ca\u00eddo <a href=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/El-Angel-Caido-Marcela-Jardon-Entrevista.pdf\" target=\"_blank\" rel=\"noopener\">&gt;&gt;&gt;<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nazules algunas cuestiones de la realidad circundante, y particularmente, las relaciones cotidianas que estamos estableciendo con la tecnolog\u00eda. Como se convierte en extensiones de nuestros cuerpos, de nuestros sentidos, de nuestras sensaciones, y como acude ante nuestras necesidades de comunicaci\u00f3n, de seguridad, de afecto, de placer, pero no deja de ser virtual, no deja de&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.marcelajardon.net\/2016\/azules\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;azules&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[20,2,265],"tags":[],"class_list":["post-267","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-azules","category-fotografia","category-azules-projects-2026","post_format-post-format-image","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/comments?post=267"}],"version-history":[{"count":10,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/267\/revisions"}],"predecessor-version":[{"id":5469,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/267\/revisions\/5469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/media\/275"}],"wp:attachment":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/media?parent=267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/categories?post=267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/tags?post=267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}