{"id":875,"date":"2016-07-14T18:21:22","date_gmt":"2016-07-14T18:21:22","guid":{"rendered":"http:\/\/www.marcelajardon.net\/2016\/?p=875"},"modified":"2026-05-05T21:33:33","modified_gmt":"2026-05-05T21:33:33","slug":"poemas-secretos-i","status":"publish","type":"post","link":"https:\/\/www.marcelajardon.net\/2016\/poemas-secretos-i\/","title":{"rendered":"poemas secretos I"},"content":{"rendered":"<p>Nudos y vac\u00edo.<br \/>\nMixta sobre tela, sobre cart\u00f3n.<br \/>\n20 x 12cm \/ 20 x 17cm<\/p>\n<p>&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.<\/p>\n<p><em>Knots and empty.<\/em><br \/>\n<em>Mixed on canvas, on cardboard.<\/em><br \/>\n<em>20 x 12cm \/ 20 x 17cm<\/em><\/p>\n<p><em>2006<\/em><\/p>\n<div id='gallery-1' class='gallery galleryid-875 gallery-columns-5 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon001a.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon001a-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon001a-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon001a-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon001a-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon001a-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon001a-350x350.jpg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_012.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_012-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_012-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_012-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_012-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_012-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_012-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top000.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top000-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top000-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top000-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top000-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top000-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top000-300x300.jpg 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon0014.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon0014-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon0014-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon0014-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon0014-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon0014-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon0014-300x300.jpg 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_001.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_001-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_001-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_001-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_001-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_001-300x300.jpg 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon004.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon004-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon004-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon004-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon004-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon004-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon004-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_010.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_010-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_010-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_010-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_010-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_010-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/Top_010-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon005.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon005-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon005-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon005-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon005-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon005-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon005-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon006.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon006-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon006-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon006-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon006-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon006-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon006-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon013.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon013-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon013-150x150.jpg 150w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon013-260x260.jpg 260w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon013-290x290.jpg 290w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon013-210x210.jpg 210w, https:\/\/www.marcelajardon.net\/2016\/wp-content\/uploads\/nudos_del_corazon013-400x400.jpg 400w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><a href=\"https:\/\/www.marcelajardon.com\/shop\/categoria-producto\/mixtas\/experimental\/\" target=\"_blank\" rel=\"noopener noreferrer\">Shop &gt;&gt;&gt;<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nNudos y vac\u00edo. Mixta sobre tela, sobre cart\u00f3n. 20 x 12cm \/ 20 x 17cm &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;. Knots and empty. Mixed on canvas, on cardboard. 20 x 12cm \/ 20 x 17cm 2006 Shop &gt;&gt;&gt; &nbsp;\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/www.marcelajardon.net\/2016\/poemas-secretos-i\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;poemas secretos I&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[287,437,84],"tags":[],"class_list":["post-875","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-poemas-secretos-pr","category-archivo-2026","category-poemas-secretos-i","post_format-post-format-gallery","entry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/comments?post=875"}],"version-history":[{"count":6,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/875\/revisions"}],"predecessor-version":[{"id":2347,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/posts\/875\/revisions\/2347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/media\/885"}],"wp:attachment":[{"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/media?parent=875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/categories?post=875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marcelajardon.net\/2016\/wp-json\/wp\/v2\/tags?post=875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}